{"id":4619,"date":"2021-03-04T14:13:39","date_gmt":"2021-03-04T17:13:39","guid":{"rendered":"http:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/?p=4619"},"modified":"2021-03-04T17:00:49","modified_gmt":"2021-03-04T20:00:49","slug":"enlaces-reunion-de-apoderados","status":"publish","type":"post","link":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/enlaces-reunion-de-apoderados\/","title":{"rendered":"Enlaces reuni\u00f3n de apoderados."},"content":{"rendered":"<p>Adjuntamos una versi\u00f3n actualizada de los enlaces para que puedan integrarse a la que le corresponda.<\/p>\n<p><!--more--><\/p>\n<p><strong>ENSE\u00d1ANZA B\u00c1SICA<\/strong><\/p>\n<a href=\"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-content\/uploads\/2021\/03\/Basica-Enlaces-reunion-de-apoderados-04-marzo-V3.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"both\" data-toolbar-fixed=\"on\">B\u00e1sica Enlaces reunion de apoderados 04 marzo V3<\/a>\n<p><a href=\"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-content\/uploads\/2021\/03\/Basica-Enlaces-reunion-de-apoderados-04-marzo-V3.pdf\"><img loading=\"lazy\" class=\" wp-image-1128 alignleft\" src=\"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-content\/uploads\/2019\/08\/descarga.png\" alt=\"\" width=\"70\" height=\"70\" srcset=\"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-content\/uploads\/2019\/08\/descarga.png 225w, https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-content\/uploads\/2019\/08\/descarga-150x150.png 150w\" sizes=\"(max-width: 70px) 100vw, 70px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-content\/uploads\/2021\/03\/Basica-Enlaces-reunion-de-apoderados-04-marzo-V3.pdf\">Enlace de descarga<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>ENSE\u00d1ANZA MEDIA<\/strong><\/p>\n<a href=\"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-content\/uploads\/2021\/03\/Media-Enlaces-reunion-de-apoderados-04-marzo-v3.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"both\" data-toolbar-fixed=\"on\">Media Enlaces reunion de apoderados 04 marzo v3<\/a>\n<p><a href=\"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-content\/uploads\/2021\/03\/Media-Enlaces-reunion-de-apoderados-04-marzo-v3.pdf\"><img loading=\"lazy\" class=\"wp-image-1128 alignleft\" src=\"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-content\/uploads\/2019\/08\/descarga.png\" alt=\"\" width=\"70\" height=\"70\" srcset=\"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-content\/uploads\/2019\/08\/descarga.png 225w, https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-content\/uploads\/2019\/08\/descarga-150x150.png 150w\" sizes=\"(max-width: 70px) 100vw, 70px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-content\/uploads\/2021\/03\/Media-Enlaces-reunion-de-apoderados-04-marzo-v3.pdf\">Enlace de descarga<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adjuntamos una versi\u00f3n actualizada de los enlaces para que puedan integrarse a la que le corresponda.<\/p>\n","protected":false},"author":1,"featured_media":4622,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/posts\/4619"}],"collection":[{"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/comments?post=4619"}],"version-history":[{"count":4,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/posts\/4619\/revisions"}],"predecessor-version":[{"id":4629,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/posts\/4619\/revisions\/4629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/media\/4622"}],"wp:attachment":[{"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/media?parent=4619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/categories?post=4619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/tags?post=4619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}