{"id":4872,"date":"2021-06-01T14:43:00","date_gmt":"2021-06-01T18:43:00","guid":{"rendered":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/?p=4872"},"modified":"2021-06-01T14:43:00","modified_gmt":"2021-06-01T18:43:00","slug":"comunicado-equipo-directivo-colegio-nueva-nazaret","status":"publish","type":"post","link":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/comunicado-equipo-directivo-colegio-nueva-nazaret\/","title":{"rendered":"Comunicado Equipo Directivo Colegio Nueva Nazaret."},"content":{"rendered":"<p style=\"text-align: center;\"><strong><span style=\"font-size: 14pt;\">SEMANA DE NIVELACI\u00d3N<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong>Lunes 7 de junio al viernes 11 de junio<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Estimados alumnos, padres y apoderados, junto con saludarlos y esperando en Dios que se encuentren bien, informamos a Uds. que tendremos una semana sin clases lectivas online y sin entrega de nuevos trabajos, con el prop\u00f3sito de generar un espacio para que aquellos alumnos que se encuentran con\u00a0 evaluaciones atrasadas o pendientes puedan colocarse al d\u00eda durante esa semana y tener tambi\u00e9n un per\u00edodo de reforzamiento y nivelaci\u00f3n con aquellos alumnos que se encuentren con sus aprendizajes descendidos.<!--more--><\/p>\n<p style=\"text-align: justify;\">Solicitamos a nuestros alumnos y alumnas que se preocupen responsablemente de utilizar este per\u00edodo para realizar todo aquello que se encuentra pendiente y de asistir a las clases de nivelaci\u00f3n online a quienes sean citados. Es importante tambi\u00e9n que nuestros apoderados motiven, supervisen y acompa\u00f1en a sus hijos durante esta semana, para lograr que ellos al finalizar esa semana se encuentren al d\u00eda con su proceso educativo.<\/p>\n<p style=\"text-align: justify;\">Invitamos tambi\u00e9n a nuestros alumnos que durante este periodo se encuentran al d\u00eda con sus notas y trabajo acad\u00e9mico, a utilizar esta semana para renovar energ\u00edas, permitirse un descanso y de este modo prepararse con nuevo \u00e1nimo para las actividades de finalizaci\u00f3n del semestre.<\/p>\n<p style=\"text-align: right;\">Atte. Equipo Directivo<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-content\/uploads\/2021\/06\/SEMANA-DE-NIVELACION-2021.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"both\" data-toolbar-fixed=\"on\">SEMANA DE NIVELACI\u00d3N 2021<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SEMANA DE NIVELACI\u00d3N Lunes 7 de junio al viernes 11 de junio Estimados alumnos, padres y apoderados, junto con saludarlos y esperando en Dios que se encuentren bien, informamos a Uds. que tendremos una semana sin clases lectivas online y sin entrega de nuevos trabajos, con el prop\u00f3sito de generar un espacio para que aquellos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2616,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/posts\/4872"}],"collection":[{"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/comments?post=4872"}],"version-history":[{"count":1,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/posts\/4872\/revisions"}],"predecessor-version":[{"id":4874,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/posts\/4872\/revisions\/4874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/media\/2616"}],"wp:attachment":[{"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/media?parent=4872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/categories?post=4872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/tags?post=4872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}