{"id":5149,"date":"2022-03-01T15:17:42","date_gmt":"2022-03-01T18:17:42","guid":{"rendered":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/?p=5149"},"modified":"2022-03-01T15:17:42","modified_gmt":"2022-03-01T18:17:42","slug":"horario-de-clases-semana-1","status":"publish","type":"post","link":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/horario-de-clases-semana-1\/","title":{"rendered":"Horario de clases semana 1"},"content":{"rendered":"<p>Estimada comunidad, ponemos a su disposici\u00f3n el horario de clases para esta semana.<\/p>\n<p>A\u00a0 partir del pr\u00f3ximo Lunes 07, comienza a correr el horario entregado por los profesores jefes el d\u00eda de hoy.<\/p>\n<a href=\"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-content\/uploads\/2022\/03\/HORARIO-SEMANA-1-DE-CLASES.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"both\" data-toolbar-fixed=\"on\">HORARIO SEMANA 1 DE CLASES<\/a>\n","protected":false},"excerpt":{"rendered":"<p>Estimada comunidad, ponemos a su disposici\u00f3n el horario de clases para esta semana. A\u00a0 partir del pr\u00f3ximo Lunes 07, comienza a correr el horario entregado por los profesores jefes el d\u00eda de hoy.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/posts\/5149"}],"collection":[{"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/comments?post=5149"}],"version-history":[{"count":2,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/posts\/5149\/revisions"}],"predecessor-version":[{"id":5153,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/posts\/5149\/revisions\/5153"}],"wp:attachment":[{"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/media?parent=5149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/categories?post=5149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colegionuevanazaret.cl\/colegiocristianopolivalente\/wp-json\/wp\/v2\/tags?post=5149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}